{"id":22131,"date":"2026-01-12T14:59:55","date_gmt":"2026-01-12T11:59:55","guid":{"rendered":"https:\/\/kelyanmedia.uz\/?page_id=22131"},"modified":"2026-01-26T00:06:57","modified_gmt":"2026-01-25T21:06:57","slug":"website-development-and-creation-in-tashkent","status":"publish","type":"page","link":"https:\/\/kelyanmedia.uz\/en\/services__trashed\/website-development-and-creation-in-tashkent\/","title":{"rendered":"\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0438 \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u0441\u0430\u0439\u0442\u043e\u0432  \u0432 \u0422\u0430\u0448\u043a\u0435\u043d\u0442\u0435 (new)"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"22131\" class=\"elementor elementor-22131\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50ab08a e-con-full e-flex e-con e-parent\" data-id=\"50ab08a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9cb3b91 e-flex e-con-boxed e-con e-child\" data-id=\"9cb3b91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a16103 elementor-widget elementor-widget-image\" data-id=\"7a16103\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"30\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/jhe45678i.svg\" class=\"attachment-large size-large wp-image-21500\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5836063 elementor-widget elementor-widget-heading\" data-id=\"5836063\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Website development and creation   <br>\n<span style=\"font-weight:100;font-style:italic\">in Tashkent<\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-513b01c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"513b01c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Every company in any business eventually needs a website. A well-designed website is not only a business card and a company&#039;s face, but also a driver of additional sales.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9366065 e-con-full e-flex e-con e-child\" data-id=\"9366065\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-07d537c elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"07d537c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIyMzUxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Calculate the project<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc0064d elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"fc0064d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#cases\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View cases<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d4d4301 e-flex e-con-boxed e-con e-child\" data-id=\"d4d4301\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d2965ef e-con-full e-flex e-con e-child\" data-id=\"d2965ef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ad4241 elementor-widget elementor-widget-heading\" data-id=\"0ad4241\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">What tasks does the website solve?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60b7bb9 elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"60b7bb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIyMzUxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get a consultation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e60d009 e-con-full e-flex e-con e-child\" data-id=\"e60d009\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab3aafd elementor-widget elementor-widget-ucaddon_content_accordion\" data-id=\"ab3aafd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_content_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Accordion -->\n<style>\/* widget: Content Accordion *\/\n\n\n\n#uc_content_accordion_elementor_ab3aafd *{\n  box-sizing: border-box;\n}\n\n#uc_content_accordion_elementor_ab3aafd .ue_heading_title{\n  margin:0;\n  flex-grow:1;\n  display:flex;\n  flex-direction:row;\n}\n\n#uc_content_accordion_elementor_ab3aafd .uc_container .uc-heading{\n\tdisplay:flex;\n    align-items:center;\n\toverflow:hidden;\n\tcursor:pointer;  \n}\n\n#uc_content_accordion_elementor_ab3aafd .uc_container .uc_content{\n    display:none;\n}\n\n#uc_content_accordion_elementor_ab3aafd .uc_container .uc-heading span.ue_accordion_icon{\n\tdisplay:flex;\n    align-items:center;\n   \tjustify-content:center;\n    flex-grow:0;\n    flex-shrink:0;\n}\n\n#uc_content_accordion_elementor_ab3aafd .uc_ac_box.uc-item-active span.uc_dactive{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_ab3aafd .uc_ac_box:not(.uc-item-active) span.uc_active{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_ab3aafd span.ue_accordion_icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_content_accordion_elementor_ab3aafd .uc_container .uc_btn {\n    text-align: center;\n    display: inline-block;\n    text-decoration: none;\n    transition: ease-in-out all 0.25s;\n}\n\n#uc_content_accordion_elementor_ab3aafd .ue-item-image img{\n  width:100%;\n  display:block;\n  object-fit:cover;\n}\n\n<\/style>\n\n<div class=\"uc_material_accordion\"  id=\"uc_content_accordion_elementor_ab3aafd\"  data-name=\"\" data-scroll=\"off\" data-offset=\"0\" data-closeothers=\"true\" data-set-hash=\"false\" data-transition-duration=\"400\" >\n  <div class=\"uc_container uc-items-wrapper\">\n    \n\n\t\t\n\n\n<div id=\"#ue-tab1\" class=\"uc_ac_box elementor-repeater-item-74a636e uc-item-active\" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect x=\"0.5\" y=\"0.5\" width=\"49\" height=\"49\" rx=\"24.5\" stroke=\"black\"><\/rect><path d=\"M16 26.0211V23.9789H23.9655V15H26.069V23.9789H34V26.0211H26.069V35H23.9655V26.0211H16Z\" fill=\"black\"><\/path><\/svg><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect width=\"50\" height=\"50\" rx=\"25\" fill=\"black\"><\/rect><rect x=\"16\" y=\"24\" width=\"18\" height=\"2\" fill=\"white\"><\/rect><\/svg><\/span>\n    <div class=\"ue_heading_title\">Increase in profits<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" style='display:block'>\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>The landing page&#039;s appearance determines customer trust and interest. The design should not only engage users but also focus their attention on the most important things.<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab2\" class=\"uc_ac_box elementor-repeater-item-daa8210\" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect x=\"0.5\" y=\"0.5\" width=\"49\" height=\"49\" rx=\"24.5\" stroke=\"black\"><\/rect><path d=\"M16 26.0211V23.9789H23.9655V15H26.069V23.9789H34V26.0211H26.069V35H23.9655V26.0211H16Z\" fill=\"black\"><\/path><\/svg><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect width=\"50\" height=\"50\" rx=\"25\" fill=\"black\"><\/rect><rect x=\"16\" y=\"24\" width=\"18\" height=\"2\" fill=\"white\"><\/rect><\/svg><\/span>\n    <div class=\"ue_heading_title\">Effective structure<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>Information needs to be organized correctly, as without it, maximum results cannot be achieved. A proper structure is essential for improving conversion.<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab3\" class=\"uc_ac_box elementor-repeater-item-40bbe2e\" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect x=\"0.5\" y=\"0.5\" width=\"49\" height=\"49\" rx=\"24.5\" stroke=\"black\"><\/rect><path d=\"M16 26.0211V23.9789H23.9655V15H26.069V23.9789H34V26.0211H26.069V35H23.9655V26.0211H16Z\" fill=\"black\"><\/path><\/svg><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect width=\"50\" height=\"50\" rx=\"25\" fill=\"black\"><\/rect><rect x=\"16\" y=\"24\" width=\"18\" height=\"2\" fill=\"white\"><\/rect><\/svg><\/span>\n    <div class=\"ue_heading_title\">Trust factors<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>Good sales are built on trust. Trust is built on honesty, genuine reviews, and recommendations.<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab4\" class=\"uc_ac_box elementor-repeater-item-d01b1f4\" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect x=\"0.5\" y=\"0.5\" width=\"49\" height=\"49\" rx=\"24.5\" stroke=\"black\"><\/rect><path d=\"M16 26.0211V23.9789H23.9655V15H26.069V23.9789H34V26.0211H26.069V35H23.9655V26.0211H16Z\" fill=\"black\"><\/path><\/svg><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect width=\"50\" height=\"50\" rx=\"25\" fill=\"black\"><\/rect><rect x=\"16\" y=\"24\" width=\"18\" height=\"2\" fill=\"white\"><\/rect><\/svg><\/span>\n    <div class=\"ue_heading_title\">Unique selling proposition<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>With a well-crafted unique selling proposition (USP), no customer can resist a lucrative and attractive promotion, discount, or any other special offer that fully demonstrates the uniqueness of a product or service.<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab5\" class=\"uc_ac_box elementor-repeater-item-bebca40\" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect x=\"0.5\" y=\"0.5\" width=\"49\" height=\"49\" rx=\"24.5\" stroke=\"black\"><\/rect><path d=\"M16 26.0211V23.9789H23.9655V15H26.069V23.9789H34V26.0211H26.069V35H23.9655V26.0211H16Z\" fill=\"black\"><\/path><\/svg><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect width=\"50\" height=\"50\" rx=\"25\" fill=\"black\"><\/rect><rect x=\"16\" y=\"24\" width=\"18\" height=\"2\" fill=\"white\"><\/rect><\/svg><\/span>\n    <div class=\"ue_heading_title\">New opportunities<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>Your website can sell around the clock, compared to stores or an office that works 5 to 2 from 9:00 to 18:00<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab6\" class=\"uc_ac_box elementor-repeater-item-f632e1f\" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect x=\"0.5\" y=\"0.5\" width=\"49\" height=\"49\" rx=\"24.5\" stroke=\"black\"><\/rect><path d=\"M16 26.0211V23.9789H23.9655V15H26.069V23.9789H34V26.0211H26.069V35H23.9655V26.0211H16Z\" fill=\"black\"><\/path><\/svg><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect width=\"50\" height=\"50\" rx=\"25\" fill=\"black\"><\/rect><rect x=\"16\" y=\"24\" width=\"18\" height=\"2\" fill=\"white\"><\/rect><\/svg><\/span>\n    <div class=\"ue_heading_title\">Answers to questions<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>Every website should have a frequently asked questions section. This will help reduce the time potential customers spend searching for the information they need and improve sales efficiency.<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab7\" class=\"uc_ac_box elementor-repeater-item-c61938b\" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect x=\"0.5\" y=\"0.5\" width=\"49\" height=\"49\" rx=\"24.5\" stroke=\"black\"><\/rect><path d=\"M16 26.0211V23.9789H23.9655V15H26.069V23.9789H34V26.0211H26.069V35H23.9655V26.0211H16Z\" fill=\"black\"><\/path><\/svg><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect width=\"50\" height=\"50\" rx=\"25\" fill=\"black\"><\/rect><rect x=\"16\" y=\"24\" width=\"18\" height=\"2\" fill=\"white\"><\/rect><\/svg><\/span>\n    <div class=\"ue_heading_title\">Improving user experience<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>By implementing new loyalty systems, cashback, and beautiful animations, you can capture customers&#039; attention and keep them on your site longer than others.<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n  <\/div>\n<\/div>\n\n\n<!-- end Content Accordion -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-db71302 e-flex e-con-boxed e-con e-child\" data-id=\"db71302\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13f8165 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"13f8165\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Which <span style=\"font-weight:100;font-style:italic\">websites <\/span>we are developing<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b08a4a8 e-con-full e-flex e-con e-child\" data-id=\"b08a4a8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9fc80a7 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"9fc80a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">One-page website<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f247cf8 elementor-widget elementor-widget-heading\" data-id=\"f247cf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">from 8,000,000 sum<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c36bf84 elementor-widget elementor-widget-heading\" data-id=\"c36bf84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">from 7 days<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9818b5b elementor-widget elementor-widget-heading\" data-id=\"9818b5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Landing Page or one-page website - is created with the purpose of collecting data from future buyers, as well as a more comprehensive presentation of a product or service<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2318eb elementor-align-justify elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"a2318eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIyMzUxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Choose<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d92bd56 e-con-full e-flex e-con e-child\" data-id=\"d92bd56\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd8ed9e elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"dd8ed9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Development of E-comm projects<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3caa18 elementor-widget elementor-widget-heading\" data-id=\"c3caa18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">from 25,000,000 sum<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f57eaa elementor-widget elementor-widget-heading\" data-id=\"4f57eaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">from 30 to 50 days<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f60d9ef elementor-widget elementor-widget-heading\" data-id=\"f60d9ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">E-commerce projects are e-commerce projects where all transactions are completed online. Each project is unique. They may include advanced features, filters, add-ons for transaction control, and much more.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34a2c91 elementor-align-justify elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"34a2c91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIyMzUxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Choose<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f2384e6 e-con-full e-flex e-con e-child\" data-id=\"f2384e6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e604bd2 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"e604bd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Turnkey corporate website<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1bdf1c elementor-widget elementor-widget-heading\" data-id=\"f1bdf1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">from 15,000,000 sum<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a2b981 elementor-widget elementor-widget-heading\" data-id=\"1a2b981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">from 15 to 25 days<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08f9ffc elementor-widget elementor-widget-heading\" data-id=\"08f9ffc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">A corporate website provides detailed information about the company: a description, the products or services it sells, terms of cooperation, contact information, and other information. Corporate websites are often created as an internal web resource for publishing information for employees.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-151e8de elementor-align-justify elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"151e8de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIyMzUxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Choose<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a388e04 e-con-full e-flex e-con e-child\" data-id=\"a388e04\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bac39ee elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"bac39ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Online store<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed5a95e elementor-widget elementor-widget-heading\" data-id=\"ed5a95e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">from 18,000,000 sum<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec6de97 elementor-widget elementor-widget-heading\" data-id=\"ec6de97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">from 20 to 35 days<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-419f608 elementor-widget elementor-widget-heading\" data-id=\"419f608\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">An online store is an online version of a store with a virtual storefront. A comprehensive approach involves creating sections for each product, its description, and offers, and implementing a CRM system. It&#039;s a great tool for increasing sales, monitoring them, expanding your customer base through newsletter subscriptions, convenient payment options, and delivery options.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b44d2c4 elementor-align-justify elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"b44d2c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIyMzUxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Choose<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0816ce4 elementor-widget elementor-widget-template\" data-id=\"0816ce4\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"cases\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"21237\" class=\"elementor elementor-21237\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-c8748a2 e-flex e-con-boxed e-con e-parent\" data-id=\"c8748a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31db717 elementor-widget elementor-widget-heading\" data-id=\"31db717\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cases<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c3048b e-con-full e-flex e-con e-child\" data-id=\"9c3048b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95ba3fa elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"95ba3fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Whether it&#039;s increasing brand awareness, increasing website traffic, or driving conversions, our portfolio demonstrates our experience delivering measurable and effective results from our clients&#039; social media marketing campaigns.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8606a7 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"f8606a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kelyanmedia.uz\/en\/works\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">All cases<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47f9936 elementor-grid-mobile-1 elementor-grid-3 elementor-grid-tablet-2 elementor-widget elementor-widget-loop-grid\" data-id=\"47f9936\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:21265,&quot;columns_mobile&quot;:1,&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:16,&quot;sizes&quot;:[]},&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;_skin&quot;:&quot;post&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-21265\">.elementor-21265 .elementor-element.elementor-element-916ce01{--display:flex;--gap:20px 20px;--row-gap:20px;--column-gap:20px;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-21265 .elementor-element.elementor-element-916ce01.e-con{--flex-grow:0;--flex-shrink:0;}.elementor-widget-theme-post-featured-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}.elementor-21265 .elementor-element.elementor-element-422cab8 img{width:100%;height:100%;object-fit:cover;object-position:center center;border-style:none;border-radius:12px 12px 12px 12px;}.elementor-widget-icon-box.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-widget-icon-box.elementor-view-framed .elementor-icon, .elementor-widget-icon-box.elementor-view-default .elementor-icon{fill:var( --e-global-color-primary );color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-widget-icon-box .elementor-icon-box-title, .elementor-widget-icon-box .elementor-icon-box-title a{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );}.elementor-widget-icon-box .elementor-icon-box-title{color:var( --e-global-color-primary );}.elementor-widget-icon-box:has(:hover) .elementor-icon-box-title,\n\t\t\t\t\t .elementor-widget-icon-box:has(:focus) .elementor-icon-box-title{color:var( --e-global-color-primary );}.elementor-widget-icon-box .elementor-icon-box-description{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );color:var( --e-global-color-text );}.elementor-21265 .elementor-element.elementor-element-d5e7bee .elementor-icon-box-wrapper{text-align:start;}.elementor-21265 .elementor-element.elementor-element-d5e7bee .elementor-icon-box-title{margin-block-end:10px;color:var( --e-global-color-bd18a55 );}.elementor-21265 .elementor-element.elementor-element-d5e7bee .elementor-icon-box-title, .elementor-21265 .elementor-element.elementor-element-d5e7bee .elementor-icon-box-title a{font-family:\"MuseoSansCyrl\", Sans-serif;font-size:16px;font-weight:300;text-transform:uppercase;line-height:1.21em;letter-spacing:0.05em;}.elementor-21265 .elementor-element.elementor-element-d5e7bee .elementor-icon-box-description{font-family:\"MuseoSansCyrl\", Sans-serif;font-size:18px;font-weight:500;line-height:1.21em;letter-spacing:0.05em;}.elementor-21265 .elementor-element.elementor-element-d5e7bee > .elementor-widget-container{padding:15px 0px 0px 0px;}@media(max-width:1024px){.elementor-widget-theme-post-featured-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}.elementor-widget-icon-box .elementor-icon-box-description{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}.elementor-21265 .elementor-element.elementor-element-d5e7bee .elementor-icon-box-title, .elementor-21265 .elementor-element.elementor-element-d5e7bee .elementor-icon-box-title a{font-size:16px;line-height:1.21em;letter-spacing:0.05em;}}@media(min-width:768px){.elementor-21265 .elementor-element.elementor-element-916ce01{--width:100%;}}@media(max-width:767px){.elementor-21265 .elementor-element.elementor-element-916ce01{--gap:16px 16px;--row-gap:16px;--column-gap:16px;}.elementor-widget-theme-post-featured-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}.elementor-widget-icon-box .elementor-icon-box-description{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}.elementor-21265 .elementor-element.elementor-element-d5e7bee .elementor-icon-box-title{margin-block-end:5px;}.elementor-21265 .elementor-element.elementor-element-d5e7bee .elementor-icon-box-title, .elementor-21265 .elementor-element.elementor-element-d5e7bee .elementor-icon-box-title a{font-size:14px;line-height:1.21em;letter-spacing:0.05em;}.elementor-21265 .elementor-element.elementor-element-d5e7bee .elementor-icon-box-description{font-size:16px;line-height:1.21em;letter-spacing:0.05em;}}\/* Start custom CSS for theme-post-featured-image, class: .elementor-element-422cab8 *\/.elementor-21265 .elementor-element.elementor-element-422cab8 img {\n    aspect-ratio: 580\/400;;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"21265\" class=\"elementor elementor-21265 e-loop-item e-loop-item-23893 post-23893 works type-works status-publish has-post-thumbnail hentry workscat-razrabotka-mobilnyh-prilozhenij\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-916ce01 e-con-full e-flex e-con e-child\" data-id=\"916ce01\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/kelyanmedia.uz\/en\/works\/fashion-app-for-selling-glasses\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-422cab8 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"422cab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1546\" height=\"1081\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/oblozhka-dlya-sajta-1.webp\" class=\"attachment-full size-full wp-image-23896\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/oblozhka-dlya-sajta-1.webp 1546w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/oblozhka-dlya-sajta-1-300x210.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/oblozhka-dlya-sajta-1-1024x716.webp 1024w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/oblozhka-dlya-sajta-1-768x537.webp 768w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/oblozhka-dlya-sajta-1-1536x1074.webp 1536w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/oblozhka-dlya-sajta-1-18x12.webp 18w\" sizes=\"(max-width: 1546px) 100vw, 1546px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5e7bee elementor-widget elementor-widget-icon-box\" data-id=\"d5e7bee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<a href=\"https:\/\/kelyanmedia.uz\/en\/workscat\/razrabotka-mobilnyh-prilozhenij\/\" rel=\"tag\">Mobile application development<\/a>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMobile app for a designer eyewear brand\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"21265\" class=\"elementor elementor-21265 e-loop-item e-loop-item-20910 post-20910 works type-works status-publish has-post-thumbnail hentry workscat-website\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-916ce01 e-con-full e-flex e-con e-child\" data-id=\"916ce01\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/kelyanmedia.uz\/en\/works\/abrau-capital\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-422cab8 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"422cab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1400\" height=\"950\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/\u201ea.webp\" class=\"attachment-full size-full wp-image-20912\" alt=\"\" srcset=\"\" sizes=\"(max-width: 1400px) 100vw, 1400px\" data-srcset=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5e7bee elementor-widget elementor-widget-icon-box\" data-id=\"d5e7bee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<a href=\"https:\/\/kelyanmedia.uz\/en\/workscat\/website\/\" rel=\"tag\">Websites<\/a>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInvestment and financial consulting\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"21265\" class=\"elementor elementor-21265 e-loop-item e-loop-item-20894 post-20894 works type-works status-publish has-post-thumbnail hentry workscat-contex\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-916ce01 e-con-full e-flex e-con e-child\" data-id=\"916ce01\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/kelyanmedia.uz\/en\/works\/real-estate\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-422cab8 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"422cab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"800\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/Frame-40.webp\" class=\"attachment-full size-full wp-image-20897\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/Frame-40.webp 1440w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/Frame-40-300x167.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/Frame-40-1024x569.webp 1024w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/Frame-40-768x427.webp 768w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/Frame-40-18x10.webp 18w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5e7bee elementor-widget elementor-widget-icon-box\" data-id=\"d5e7bee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<a href=\"https:\/\/kelyanmedia.uz\/en\/workscat\/context-2\/\" rel=\"tag\">Contextual advertising<\/a>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tReal estate\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"21265\" class=\"elementor elementor-21265 e-loop-item e-loop-item-20873 post-20873 works type-works status-publish has-post-thumbnail hentry workscat-contex\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-916ce01 e-con-full e-flex e-con e-child\" data-id=\"916ce01\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/kelyanmedia.uz\/en\/works\/pawnshop-of-household-appliances\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-422cab8 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"422cab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"800\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/Frame-34.webp\" class=\"attachment-full size-full wp-image-20858\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/Frame-34.webp 1440w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/Frame-34-300x167.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/Frame-34-1024x569.webp 1024w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/Frame-34-768x427.webp 768w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/12\/Frame-34-18x10.webp 18w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5e7bee elementor-widget elementor-widget-icon-box\" data-id=\"d5e7bee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<a href=\"https:\/\/kelyanmedia.uz\/en\/workscat\/context-2\/\" rel=\"tag\">Contextual advertising<\/a>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tHousehold appliance pawn shop\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"21265\" class=\"elementor elementor-21265 e-loop-item e-loop-item-20851 post-20851 works type-works status-publish has-post-thumbnail hentry workscat-seo\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-916ce01 e-con-full e-flex e-con e-child\" data-id=\"916ce01\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/kelyanmedia.uz\/en\/works\/dentistry\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-422cab8 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"422cab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"800\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/11\/Frame-29-1.webp\" class=\"attachment-full size-full wp-image-20852\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/11\/Frame-29-1.webp 1440w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/11\/Frame-29-1-300x167.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/11\/Frame-29-1-1024x569.webp 1024w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/11\/Frame-29-1-768x427.webp 768w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/11\/Frame-29-1-18x10.webp 18w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5e7bee elementor-widget elementor-widget-icon-box\" data-id=\"d5e7bee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<a href=\"https:\/\/kelyanmedia.uz\/en\/workscat\/seo\/\" rel=\"tag\">SEO optimization<\/a>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDentistry\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"21265\" class=\"elementor elementor-21265 e-loop-item e-loop-item-20823 post-20823 works type-works status-publish has-post-thumbnail hentry workscat-seo\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-916ce01 e-con-full e-flex e-con e-child\" data-id=\"916ce01\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/kelyanmedia.uz\/en\/works\/glo-tobacco-heating-system\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-422cab8 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"422cab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"800\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/11\/Frame-10-1.webp\" class=\"attachment-full size-full wp-image-20829\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/11\/Frame-10-1.webp 1440w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/11\/Frame-10-1-300x167.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/11\/Frame-10-1-1024x569.webp 1024w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/11\/Frame-10-1-768x427.webp 768w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2025\/11\/Frame-10-1-18x10.webp 18w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5e7bee elementor-widget elementor-widget-icon-box\" data-id=\"d5e7bee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<a href=\"https:\/\/kelyanmedia.uz\/en\/workscat\/seo\/\" rel=\"tag\">SEO optimization<\/a>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGLO tobacco heating system\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73f7e75 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"73f7e75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"716\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-1024x917.webp\" class=\"attachment-large size-large wp-image-21278\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-1024x917.webp 1024w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-300x269.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-768x688.webp 768w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-13x12.webp 13w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008.webp 1481w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcb8b6c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"bcb8b6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"716\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-1024x917.webp\" class=\"attachment-large size-large wp-image-21278\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-1024x917.webp 1024w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-300x269.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-768x688.webp 768w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-13x12.webp 13w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008.webp 1481w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8093bbe elementor-widget elementor-widget-template\" data-id=\"8093bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"21310\" class=\"elementor elementor-21310\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-b4b74b7 e-flex e-con-boxed e-con e-parent\" data-id=\"b4b74b7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5355368 elementor-widget elementor-widget-heading\" data-id=\"5355368\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Submit a request<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-196f06d elementor-widget elementor-widget-heading\" data-id=\"196f06d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Submit a request, and our expert will conduct an express audit of your niche in Tashkent and prepare a media plan within 24 hours.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68f6954 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"68f6954\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;33&quot;,&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"21310\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"68f6954\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Kelyanmedia\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-33 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-phone elementor-col-33 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-phone\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelephone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<span class=\"ccfef-editor-intl-input\" data-id=\"form-field-phone\" data-field-id=\"f1b30a9\" data-default-country=\"uz\" data-include-countries=\"\" data-exclude-countries=\"\" data-dial-code-visibility=\"show\" data-strict-mode=\"no\" style=\"display: none;\"><\/span>\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[phone]\" id=\"form-field-phone\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_source elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_source]\" id=\"form-field-utm_source\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_content elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_content]\" id=\"form-field-utm_content\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_medium elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_medium]\" id=\"form-field-utm_medium\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_campaign elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_campaign]\" id=\"form-field-utm_campaign\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_term elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_term]\" id=\"form-field-utm_term\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-33 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discuss the project<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a084948 e-flex e-con-boxed e-con e-child\" data-id=\"a084948\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6286b94 elementor-widget elementor-widget-heading\" data-id=\"6286b94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Stages of work<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ba69d3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"2ba69d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">We structure the development process so that every technical stage contributes to the website&#039;s future visibility in AI search and traditional SEO, ensuring your brand&#039;s leadership in the Uzbek market.\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cbd26ec e-con-full e-flex e-con e-child\" data-id=\"cbd26ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b24d1b3 e-con-full step-flex-item e-flex e-con e-child\" data-id=\"b24d1b3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-958cbfd elementor-widget__width-initial elementor-widget-mobile__width-inherit step-flex-title elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"958cbfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_958cbfd .circle_number_widget_layout{\n  display:flex;\n  }\n\n#uc_circle_number_widget_elementor_958cbfd .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_958cbfd .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(0deg);\n    }\n\n#uc_circle_number_widget_elementor_958cbfd .circle_number_text{\n  transform:rotate(-0deg);\n}\n\n#uc_circle_number_widget_elementor_958cbfd .ue-number-container, \n#uc_circle_number_widget_elementor_958cbfd .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_958cbfd {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_958cbfd\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">01<\/div>\n        <\/div>\n      <\/div>\n\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Design<\/div>              <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ffc17a7 e-con-full e-flex e-con e-child\" data-id=\"ffc17a7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0366833 step-flex-img elementor-widget elementor-widget-image\" data-id=\"0366833\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"225\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3.webp\" class=\"attachment-large size-large wp-image-22499\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3.webp 750w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3-300x90.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3-18x5.webp 18w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c46da68 step-flex-text elementor-widget elementor-widget-heading\" data-id=\"c46da68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">We begin with a deep dive into the business: we analyze demand in Tashkent and the surrounding regions, and we study competitors and their link strategies. We develop a website architecture that is compliant with SGE (Search Generative Experience) requirements from the start, creating a logical content map for users and neural networks.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47bf152 e-con-full step-flex-item e-flex e-con e-child\" data-id=\"47bf152\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da3dfe2 elementor-widget__width-initial elementor-widget-mobile__width-inherit step-flex-title elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"da3dfe2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_da3dfe2 .circle_number_widget_layout{\n  display:flex;\n  }\n\n#uc_circle_number_widget_elementor_da3dfe2 .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_da3dfe2 .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(0deg);\n    }\n\n#uc_circle_number_widget_elementor_da3dfe2 .circle_number_text{\n  transform:rotate(-0deg);\n}\n\n#uc_circle_number_widget_elementor_da3dfe2 .ue-number-container, \n#uc_circle_number_widget_elementor_da3dfe2 .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_da3dfe2 {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_da3dfe2\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">02<\/div>\n        <\/div>\n      <\/div>\n\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Design<\/div>              <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7925c5 e-con-full e-flex e-con e-child\" data-id=\"b7925c5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1e8131 step-flex-img elementor-widget elementor-widget-image\" data-id=\"e1e8131\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"225\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3.webp\" class=\"attachment-large size-large wp-image-22499\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3.webp 750w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3-300x90.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3-18x5.webp 18w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63fb8a6 step-flex-text elementor-widget elementor-widget-heading\" data-id=\"63fb8a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">We create more than just a pretty image; we create a high-converting interface that takes Core Web Vitals into account. We implement interactive elements that Google considers when evaluating quality (UX\/UI). The design adapts to all device types, ensuring perfect display and speed of interaction.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67a7079 e-con-full step-flex-item e-flex e-con e-child\" data-id=\"67a7079\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4603cb elementor-widget__width-initial elementor-widget-mobile__width-inherit step-flex-title elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"d4603cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_d4603cb .circle_number_widget_layout{\n  display:flex;\n  }\n\n#uc_circle_number_widget_elementor_d4603cb .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_d4603cb .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(0deg);\n    }\n\n#uc_circle_number_widget_elementor_d4603cb .circle_number_text{\n  transform:rotate(-0deg);\n}\n\n#uc_circle_number_widget_elementor_d4603cb .ue-number-container, \n#uc_circle_number_widget_elementor_d4603cb .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_d4603cb {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_d4603cb\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">03<\/div>\n        <\/div>\n      <\/div>\n\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Technical implementation<\/div>              <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37e88b0 e-con-full e-flex e-con e-child\" data-id=\"37e88b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e52cfb step-flex-img elementor-widget elementor-widget-image\" data-id=\"3e52cfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"225\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3.webp\" class=\"attachment-large size-large wp-image-22499\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3.webp 750w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3-300x90.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3-18x5.webp 18w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4ea21f step-flex-text elementor-widget elementor-widget-heading\" data-id=\"f4ea21f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">We transform mockups into clean, valid code optimized for instant loading. At this stage, we integrate complex micro-markup (Schema.org, JSON-LD), which explains the essence of your business, services, and benefits to search engines and AI models to accurately target search results.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5918b6b e-con-full step-flex-item e-flex e-con e-child\" data-id=\"5918b6b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-524d1ad elementor-widget__width-initial elementor-widget-mobile__width-inherit step-flex-title elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"524d1ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_524d1ad .circle_number_widget_layout{\n  display:flex;\n  }\n\n#uc_circle_number_widget_elementor_524d1ad .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_524d1ad .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(0deg);\n    }\n\n#uc_circle_number_widget_elementor_524d1ad .circle_number_text{\n  transform:rotate(-0deg);\n}\n\n#uc_circle_number_widget_elementor_524d1ad .ue-number-container, \n#uc_circle_number_widget_elementor_524d1ad .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_524d1ad {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_524d1ad\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">04<\/div>\n        <\/div>\n      <\/div>\n\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Filling<\/div>              <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9795d53 e-con-full e-flex e-con e-child\" data-id=\"9795d53\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f2eabd step-flex-img elementor-widget elementor-widget-image\" data-id=\"2f2eabd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"225\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3.webp\" class=\"attachment-large size-large wp-image-22499\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3.webp 750w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3-300x90.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3-18x5.webp 18w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1293635 step-flex-text elementor-widget elementor-widget-heading\" data-id=\"1293635\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">We fill pages with unique, expert content that meets the EEAT (Experience, Expertise, Authority, Trust) criteria. We create content that addresses customer pain points and includes LSI keywords, allowing the website to rank for the widest possible range of target queries.\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c744334 e-con-full step-flex-item e-flex e-con e-child\" data-id=\"c744334\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0156d0 elementor-widget__width-initial elementor-widget-mobile__width-inherit step-flex-title elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"b0156d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_b0156d0 .circle_number_widget_layout{\n  display:flex;\n  }\n\n#uc_circle_number_widget_elementor_b0156d0 .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_b0156d0 .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(0deg);\n    }\n\n#uc_circle_number_widget_elementor_b0156d0 .circle_number_text{\n  transform:rotate(-0deg);\n}\n\n#uc_circle_number_widget_elementor_b0156d0 .ue-number-container, \n#uc_circle_number_widget_elementor_b0156d0 .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_b0156d0 {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_b0156d0\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">05<\/div>\n        <\/div>\n      <\/div>\n\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Release and promotion<\/div>              <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-465fe66 e-con-full e-flex e-con e-child\" data-id=\"465fe66\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46e7cf6 step-flex-img elementor-widget elementor-widget-image\" data-id=\"46e7cf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"225\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3.webp\" class=\"attachment-large size-large wp-image-22499\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3.webp 750w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3-300x90.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/1231dizajn-bez-nazvaniya-16-3-18x5.webp 18w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2abff8 step-flex-text elementor-widget elementor-widget-heading\" data-id=\"c2abff8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">We launch the project and conduct final security and speed testing. After launch, we move on to the active SEO phase: building authority in the .uz domain zone and monitoring Google&#039;s generative search rankings to ensure your website consistently maintains top rankings and generates real leads.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-524a420 e-flex e-con-boxed e-con e-child\" data-id=\"524a420\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f14c9d elementor-widget elementor-widget-heading\" data-id=\"9f14c9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Why exactly?<span style=\"font-weight:100;font-style:italic\">We<\/span>?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-639c235 e-grid e-con-full e-con e-child\" data-id=\"639c235\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-abfd8ea e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"abfd8ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa44399 e-con-full e-flex e-con e-child\" data-id=\"aa44399\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b72fb2 elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"1b72fb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_1b72fb2 .circle_number_widget_layout{\n  display:flex;\n       align-items:center;\n  }\n\n#uc_circle_number_widget_elementor_1b72fb2 .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_1b72fb2 .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(0deg);\n    }\n\n#uc_circle_number_widget_elementor_1b72fb2 .circle_number_text{\n  transform:rotate(-0deg);\n}\n\n#uc_circle_number_widget_elementor_1b72fb2 .ue-number-container, \n#uc_circle_number_widget_elementor_1b72fb2 .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_1b72fb2 {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_1b72fb2\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">01<\/div>\n        <\/div>\n      <\/div>\n\n              <div class=\"ue-spacing\"><\/div>\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Solving a business problem<\/div>              <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4494d3e elementor-widget elementor-widget-heading\" data-id=\"4494d3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">We don&#039;t just develop a website; we solve your business problems. This results in a website that delivers results: attracting leads, increasing sales, and enhancing brand awareness.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c3e2efa e-con-full e-flex e-con e-child\" data-id=\"c3e2efa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb32aff elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"bb32aff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_bb32aff .circle_number_widget_layout{\n  display:flex;\n       align-items:center;\n  }\n\n#uc_circle_number_widget_elementor_bb32aff .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_bb32aff .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(0deg);\n    }\n\n#uc_circle_number_widget_elementor_bb32aff .circle_number_text{\n  transform:rotate(-0deg);\n}\n\n#uc_circle_number_widget_elementor_bb32aff .ue-number-container, \n#uc_circle_number_widget_elementor_bb32aff .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_bb32aff {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_bb32aff\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">02<\/div>\n        <\/div>\n      <\/div>\n\n              <div class=\"ue-spacing\"><\/div>\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Development of any complexity<\/div>              <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-531e2a3 elementor-widget elementor-widget-heading\" data-id=\"531e2a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">We create landing pages, corporate websites, online stores, and catalogs\u2014to suit any business purpose and scale.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0bcddaa e-con-full e-flex e-con e-child\" data-id=\"0bcddaa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1bcc3aa elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"1bcc3aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_1bcc3aa .circle_number_widget_layout{\n  display:flex;\n       align-items:center;\n  }\n\n#uc_circle_number_widget_elementor_1bcc3aa .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_1bcc3aa .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(0deg);\n    }\n\n#uc_circle_number_widget_elementor_1bcc3aa .circle_number_text{\n  transform:rotate(-0deg);\n}\n\n#uc_circle_number_widget_elementor_1bcc3aa .ue-number-container, \n#uc_circle_number_widget_elementor_1bcc3aa .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_1bcc3aa {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_1bcc3aa\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">03<\/div>\n        <\/div>\n      <\/div>\n\n              <div class=\"ue-spacing\"><\/div>\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Unique design<\/div>              <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2a5e74 elementor-widget elementor-widget-heading\" data-id=\"b2a5e74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">We create every layout from scratch. We create a design that highlights the company&#039;s character and creates the right impression from the very first moment.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65f3b39 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"65f3b39\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4da8673 e-con-full e-flex e-con e-child\" data-id=\"4da8673\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-011bca5 elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"011bca5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_011bca5 .circle_number_widget_layout{\n  display:flex;\n       align-items:center;\n  }\n\n#uc_circle_number_widget_elementor_011bca5 .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_011bca5 .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(0deg);\n    }\n\n#uc_circle_number_widget_elementor_011bca5 .circle_number_text{\n  transform:rotate(-0deg);\n}\n\n#uc_circle_number_widget_elementor_011bca5 .ue-number-container, \n#uc_circle_number_widget_elementor_011bca5 .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_011bca5 {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_011bca5\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">04<\/div>\n        <\/div>\n      <\/div>\n\n              <div class=\"ue-spacing\"><\/div>\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">A team of professionals<\/div>              <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e48def5 elementor-widget elementor-widget-heading\" data-id=\"e48def5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">The project involves designers, developers, copywriters, and marketers with relevant education and experience in the digital field.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-266dde3 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"266dde3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f076e8 e-con-full e-flex e-con e-child\" data-id=\"7f076e8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bd8eb5 elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"4bd8eb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_4bd8eb5 .circle_number_widget_layout{\n  display:flex;\n       align-items:center;\n  }\n\n#uc_circle_number_widget_elementor_4bd8eb5 .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_4bd8eb5 .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(0deg);\n    }\n\n#uc_circle_number_widget_elementor_4bd8eb5 .circle_number_text{\n  transform:rotate(-0deg);\n}\n\n#uc_circle_number_widget_elementor_4bd8eb5 .ue-number-container, \n#uc_circle_number_widget_elementor_4bd8eb5 .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_4bd8eb5 {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_4bd8eb5\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">05<\/div>\n        <\/div>\n      <\/div>\n\n              <div class=\"ue-spacing\"><\/div>\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Turnkey website\u00ab<\/div>              <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7b8bde elementor-widget elementor-widget-heading\" data-id=\"c7b8bde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">We handle everything: text, graphics, technical support, integrations, basic SEO, and analytics setup. You&#039;ll receive a fully-launchable website.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-165e4c0 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"165e4c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-490d03b e-flex e-con-boxed e-con e-child\" data-id=\"490d03b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-291b437 e-con-full e-flex e-con e-child\" data-id=\"291b437\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5b83fa elementor-widget elementor-widget-heading\" data-id=\"b5b83fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Why <span style=\"font-weight:100;font-style:italic\">they trust us <\/span>budgets from $100,000?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92ce0e1 elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"92ce0e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIyMzUxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Calculate growth potential<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-367640b e-con-full e-flex e-con e-child\" data-id=\"367640b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb02f39 elementor-widget elementor-widget-icon-box\" data-id=\"bb02f39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSenior level team\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tYour project is handled by experts with 5+ years of niche experience. We don&#039;t delegate tasks to interns\u2014each strategy is overseen by a dedicated specialist who has worked with market leaders in Uzbekistan.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d76e4cb elementor-widget elementor-widget-icon-box\" data-id=\"d76e4cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t85% \u2014 Customer Loyalty Index\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMost clients come to us through referrals. We value our reputation and build processes to ensure the service is as high-quality as the results.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-212dc89 elementor-widget elementor-widget-icon-box\" data-id=\"212dc89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t11 months is the average length of service\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWe don&#039;t focus on one-time reach. Our goal is long-term partnerships. We grow with your business, constantly optimizing your cost per lead and increasing your profits.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4648ff6 elementor-widget elementor-widget-icon-box\" data-id=\"4648ff6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAI- and Data-Driven Marketing\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tIn 2026, we&#039;ll be using neural networks for predictive analytics and GEO optimization. This allows us to find target audiences faster and more cost-effectively than traditional agencies.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62734c0 elementor-widget elementor-widget-icon-box\" data-id=\"62734c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t100% budget transparency\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tYou see every amount spent in real time. We provide 24\/7 access to dashboards and weekly reports on your business&#039;s key KPIs.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6736ad2 elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"6736ad2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIyMzUxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Calculate growth potential<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7989d13 e-flex e-con-boxed e-con e-child\" data-id=\"7989d13\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c1fba2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"8c1fba2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Web Development Team<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0ebaebf e-con-full e-flex e-con e-child\" data-id=\"0ebaebf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ef831d7 e-con-full e-flex e-con e-child\" data-id=\"ef831d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c76e731 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c76e731\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/12qellipse-2.webp\" class=\"attachment-full size-full wp-image-22974\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/12qellipse-2.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/12qellipse-2-150x150.webp 150w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/12qellipse-2-12x12.webp 12w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\">Sunnat Tumanov<\/div><p class=\"elementor-image-box-description\">Head of UX\/UI team<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fbdf7e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2fbdf7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\" fill=\"none\"><circle cx=\"8\" cy=\"8\" r=\"8\" fill=\"#FF8060\"><\/circle><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Successfully implemented projects for large corporations and startups<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\" fill=\"none\"><circle cx=\"8\" cy=\"8\" r=\"8\" fill=\"#FF8060\"><\/circle><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Studied at the leading international school of UX\/UI designers \u2013 UPROCK<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\" fill=\"none\"><circle cx=\"8\" cy=\"8\" r=\"8\" fill=\"#FF8060\"><\/circle><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Experience working with various niches: from dental clinics to government institutions  <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0229c0b e-con-full e-grid e-con e-child\" data-id=\"0229c0b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d08af90 e-con-full e-flex e-con e-child\" data-id=\"d08af90\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43d06d2 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"43d06d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewbox=\"0 0 48 48\" fill=\"none\"><path d=\"M18 22V40M18 22H9.19922C8.07911 22 7.51962 22 7.0918 22.218C6.71547 22.4097 6.40973 22.7155 6.21799 23.0918C6 23.5196 6 24.0801 6 25.2002V40H18M18 22V11.2002C18 10.0801 18 9.51962 18.218 9.0918C18.4097 8.71547 18.7155 8.40973 19.0918 8.21799C19.5196 8 20.0791 8 21.1992 8H26.7992C27.9193 8 28.4806 8 28.9084 8.21799C29.2847 8.40973 29.5895 8.71547 29.7812 9.0918C29.9992 9.51962 30 10.0801 30 11.2002V16M18 40H30M30 40L42 40.0002V19.2002C42 18.0801 41.9992 17.5196 41.7812 17.0918C41.5895 16.7155 41.2859 16.4097 40.9095 16.218C40.4817 16 39.9201 16 38.8 16H30M30 40V16\" stroke=\"#FF8060\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProject Manager\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b014944 e-con-full e-flex e-con e-child\" data-id=\"b014944\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1180c8 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b1180c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewbox=\"0 0 48 48\" fill=\"none\"><path d=\"M6 30.0005V33.6C6 35.8402 6 36.9595 6.43597 37.8152C6.81947 38.5678 7.43095 39.181 8.18359 39.5645C9.0384 40 10.158 40 12.3938 40H42.0004M6 30.0005V10M6 30.0005L13.7068 23.5781L13.7132 23.573C15.1073 22.4112 15.8058 21.8292 16.5631 21.5928C17.4577 21.3135 18.4214 21.3577 19.2871 21.7168C20.021 22.0212 20.6645 22.6648 21.9515 23.9518L21.9644 23.9647C23.2714 25.2717 23.9267 25.9269 24.6723 26.2307C25.5547 26.5902 26.5371 26.6211 27.4414 26.3211C28.2081 26.0668 28.9084 25.4551 30.3086 24.2299L41.9999 14\" stroke=\"#FF8060\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWeb designer\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-262bc64 e-con-full e-flex e-con e-child\" data-id=\"262bc64\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dc57d7 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2dc57d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewbox=\"0 0 48 48\" fill=\"none\"><path d=\"M20.0004 8H14.4004C12.1602 8 11.0392 8 10.1836 8.43597C9.43095 8.81947 8.81947 9.43095 8.43597 10.1836C8 11.0392 8 12.1602 8 14.4004V33.6004C8 35.8406 8 36.9601 8.43597 37.8158C8.81947 38.5684 9.43095 39.181 10.1836 39.5645C11.0384 40 12.158 40 14.3938 40H33.6062C35.842 40 36.96 40 37.8148 39.5645C38.5674 39.181 39.181 38.5678 39.5645 37.8152C40 36.9604 40 35.842 40 33.6062V28M32 10L20 22V28H26L38 16M32 10L38 4L44 10L38 16M32 10L38 16\" stroke=\"#FF8060\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tBack-end developer\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a41428 e-con-full e-flex e-con e-child\" data-id=\"4a41428\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad6aed9 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ad6aed9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewbox=\"0 0 48 48\" fill=\"none\"><path d=\"M40 42C40 36.4772 32.8366 32 24 32C15.1634 32 8 36.4772 8 42M24 26C18.4772 26 14 21.5228 14 16C14 10.4772 18.4772 6 24 6C29.5228 6 34 10.4772 34 16C34 21.5228 29.5228 26 24 26Z\" stroke=\"#FF8060\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFront-end developer\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-972276e e-con-full e-flex e-con e-child\" data-id=\"972276e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b231e4 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1b231e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewbox=\"0 0 48 48\" fill=\"none\"><path d=\"M18.3436 29.6585L29.6573 18.3448M14.1017 22.587L11.2733 25.4154C8.14909 28.5396 8.14819 33.6053 11.2724 36.7295C14.3966 39.8537 19.4634 39.8528 22.5876 36.7286L25.413 33.9005M22.5858 14.101L25.4142 11.2726C28.5384 8.14836 33.6031 8.14892 36.7273 11.2731C39.8515 14.3973 39.8514 19.4627 36.7272 22.5869L33.9002 25.4152\" stroke=\"#FF8060\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tContent Manager\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9644563 e-con-full e-flex e-con e-child\" data-id=\"9644563\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c43f5c9 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c43f5c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewbox=\"0 0 48 48\" fill=\"none\"><path d=\"M30 12V42M30 12L42 6V36L30 42M30 12L18 6M30 42L18 36M18 36L6 42V12L18 6M18 36V6\" stroke=\"#FF8060\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNative speaker proofreader\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-343b053 elementor-widget elementor-widget-template\" data-id=\"343b053\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"21336\" class=\"elementor elementor-21336\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-c36ddc4 e-flex e-con-boxed e-con e-parent\" data-id=\"c36ddc4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72f9a85 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"72f9a85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Us\n<span style=\"font-weight:100;font-style:italic\">\ntrust<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f701bcb elementor-widget elementor-widget-image-carousel\" data-id=\"f701bcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_show_tablet&quot;:&quot;4&quot;,&quot;slides_to_show_mobile&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:0,&quot;speed&quot;:3500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133046112fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133046112fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133046012fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133046012fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133045912fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133045912fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133045412fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133045412fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133045612fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133045612fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133045812fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133045812fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133045512fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133045512fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133045712fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133045712fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133045312fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133045312fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133045112fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133045112fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133045212fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133045212fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133045012fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133045012fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133044912fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133044912fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133044812fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133044812fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-213133043412fjiwqnufbuy1r21fqwfwqf12-300x99.webp\" alt=\"Frame 213133043412fjiwqnufbuy1r21fqwfwqf12\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8a2903 elementor-widget elementor-widget-image-carousel\" data-id=\"a8a2903\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_show_tablet&quot;:&quot;4&quot;,&quot;slides_to_show_mobile&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:0,&quot;speed&quot;:3500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"rtl\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330460ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330460ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330453ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330453ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330451ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330451ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330450ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330450ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330461ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330461ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330459ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330459ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330454ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330454ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330456ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330456ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330458ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330458ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330452ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330452ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330455ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330455ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330449ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330449ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330448ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330448ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330434ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330434ewgjjg13u134u124--1-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 out of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/frame-2131330457ewgjjg13u134u124-1--300x99.webp\" alt=\"Frame 2131330457ewgjjg13u134u124--1-\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bca52ef e-flex e-con-boxed e-con e-child\" data-id=\"bca52ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f07480 elementor-widget elementor-widget-heading\" data-id=\"4f07480\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We are building <span style=\"font-weight:100;font-style:italic\">long-term  <\/span>relationship<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-caeef27 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"caeef27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"860\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/xdcfvghj-953x1024.webp\" class=\"attachment-large size-large wp-image-21345\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/xdcfvghj-953x1024.webp 953w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/xdcfvghj-279x300.webp 279w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/xdcfvghj-768x826.webp 768w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/xdcfvghj-11x12.webp 11w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/xdcfvghj.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c161228 e-grid e-con-full e-con e-child\" data-id=\"c161228\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ff9c52 elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"9ff9c52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_9ff9c52 .circle_number_widget_layout{\n  display:flex;\n  }\n\n#uc_circle_number_widget_elementor_9ff9c52 .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_9ff9c52 .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(deg);\n    }\n\n#uc_circle_number_widget_elementor_9ff9c52 .circle_number_text{\n  transform:rotate(-deg);\n}\n\n#uc_circle_number_widget_elementor_9ff9c52 .ue-number-container, \n#uc_circle_number_widget_elementor_9ff9c52 .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_9ff9c52 {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_9ff9c52\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">01<\/div>\n        <\/div>\n      <\/div>\n\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">We work under a contract<\/div>        <div class=\"ue-description\">We don&#039;t just create a contract, but attach technical specifications with all the functionality and deadlines.<\/div>      <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-290708e elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"290708e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_290708e .circle_number_widget_layout{\n  display:flex;\n  }\n\n#uc_circle_number_widget_elementor_290708e .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_290708e .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(deg);\n    }\n\n#uc_circle_number_widget_elementor_290708e .circle_number_text{\n  transform:rotate(-deg);\n}\n\n#uc_circle_number_widget_elementor_290708e .ue-number-container, \n#uc_circle_number_widget_elementor_290708e .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_290708e {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_290708e\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">02<\/div>\n        <\/div>\n      <\/div>\n\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Staged payment system<\/div>        <div class=\"ue-description\">If the cost of a website exceeds the average, we distribute the payment into several parts: 30\/20\/30\/20 or 70\/30<\/div>      <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a81cb1 elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"3a81cb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_3a81cb1 .circle_number_widget_layout{\n  display:flex;\n  }\n\n#uc_circle_number_widget_elementor_3a81cb1 .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_3a81cb1 .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(deg);\n    }\n\n#uc_circle_number_widget_elementor_3a81cb1 .circle_number_text{\n  transform:rotate(-deg);\n}\n\n#uc_circle_number_widget_elementor_3a81cb1 .ue-number-container, \n#uc_circle_number_widget_elementor_3a81cb1 .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_3a81cb1 {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_3a81cb1\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">03<\/div>\n        <\/div>\n      <\/div>\n\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">We value our clients<\/div>        <div class=\"ue-description\">We work through communication channels that are convenient for you.<\/div>      <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-383e605 elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"383e605\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_383e605 .circle_number_widget_layout{\n  display:flex;\n  }\n\n#uc_circle_number_widget_elementor_383e605 .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_383e605 .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(deg);\n    }\n\n#uc_circle_number_widget_elementor_383e605 .circle_number_text{\n  transform:rotate(-deg);\n}\n\n#uc_circle_number_widget_elementor_383e605 .ue-number-container, \n#uc_circle_number_widget_elementor_383e605 .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_383e605 {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_383e605\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">04<\/div>\n        <\/div>\n      <\/div>\n\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Each project is unique<\/div>        <div class=\"ue-description\">The code is written by experienced professionals and each project is developed from scratch without the use of templates.<\/div>      <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21e4564 elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"21e4564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_21e4564 .circle_number_widget_layout{\n  display:flex;\n  }\n\n#uc_circle_number_widget_elementor_21e4564 .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_21e4564 .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(deg);\n    }\n\n#uc_circle_number_widget_elementor_21e4564 .circle_number_text{\n  transform:rotate(-deg);\n}\n\n#uc_circle_number_widget_elementor_21e4564 .ue-number-container, \n#uc_circle_number_widget_elementor_21e4564 .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_21e4564 {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_21e4564\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">05<\/div>\n        <\/div>\n      <\/div>\n\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Escort <\/div>        <div class=\"ue-description\">We help with mastering the functionality and record individual video materials for working with the admin panel.<\/div>      <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89739b2 elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"89739b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_89739b2 .circle_number_widget_layout{\n  display:flex;\n  }\n\n#uc_circle_number_widget_elementor_89739b2 .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_89739b2 .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(deg);\n    }\n\n#uc_circle_number_widget_elementor_89739b2 .circle_number_text{\n  transform:rotate(-deg);\n}\n\n#uc_circle_number_widget_elementor_89739b2 .ue-number-container, \n#uc_circle_number_widget_elementor_89739b2 .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_89739b2 {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_89739b2\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">06<\/div>\n        <\/div>\n      <\/div>\n\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">We don&#039;t violate deadlines<\/div>        <div class=\"ue-description\">Thanks to a well-thought-out and effective project management system, we strictly monitor deadlines.<\/div>      <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95aa347 elementor-widget elementor-widget-ucaddon_circle_number_widget\" data-id=\"95aa347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_circle_number_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Number Box -->\n<style>\/* widget: Number Box *\/\n\n#uc_circle_number_widget_elementor_95aa347 .circle_number_widget_layout{\n  display:flex;\n  }\n\n#uc_circle_number_widget_elementor_95aa347 .circle_number_widget_container_link{\n  display:block;\n}\n\n#uc_circle_number_widget_elementor_95aa347 .circle_number_widget{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  position:relative;\n  transform:rotate(deg);\n    }\n\n#uc_circle_number_widget_elementor_95aa347 .circle_number_text{\n  transform:rotate(-deg);\n}\n\n#uc_circle_number_widget_elementor_95aa347 .ue-number-container, \n#uc_circle_number_widget_elementor_95aa347 .ue-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n.circle_number_widget{\n  font-size:32px;\n}\n\n.ue-title{\n  font-size:21px;\n}\n\n@keyframes pulseuc_circle_number_widget_elementor_95aa347 {\n\t 0% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n\t\n\t70% {\n\t\ttransform: scale(1);\n\t\tbox-shadow: 0 0 0 20px #b6b6b6;\n\t}\n\t\n\t100% {\n\t\ttransform: scale(0.95);\n\t\tbox-shadow: 0 0 0 0 #b6b6b6;\n\t}\n}\n\n<\/style>\n\n<div id=\"uc_circle_number_widget_elementor_95aa347\" class=\"circle_number_widget_container\" role=\"group\">\n  \n      <div class=\"circle_number_widget_layout\">\n      \n      <div class=\"ue-number-container\"> \n        <div class=\"circle_number_widget\">\n          <div class=\"circle_number_text\">07<\/div>\n        <\/div>\n      <\/div>\n\n      \n      <div class=\"ue-widget-content\">\n        <div class=\"ue-title\">Customer focus<\/div>        <div class=\"ue-description\">We thoroughly study your niche, write out a preliminary work plan, coordinate everything, and only then draw up an estimate and contract.<\/div>      <\/div>  \n  \n    <\/div>\n  <\/div>\n<!-- end Number Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24867ec e-flex e-con-boxed e-con e-child\" data-id=\"24867ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b66e388 e-con-full e-flex e-con e-child\" data-id=\"b66e388\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7de01bd e-con-full e-flex e-con e-child\" data-id=\"7de01bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eece624 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"eece624\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Brief for calculation <br>\n<span style=\"font-weight:100;font-style:italic\">\ncost<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8e3027 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"a8e3027\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Answer a few questions to calculate the cost of our services. We&#039;ll find solutions tailored to your needs and budget.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-922e35a e-con-full e-flex e-con e-child\" data-id=\"922e35a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-edd70fa elementor-button-align-stretch elementor-widget elementor-widget-global elementor-global-21470 elementor-widget-form\" data-id=\"edd70fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;\\u0414\\u0430\\u043b\\u0435\\u0435&quot;,&quot;step_previous_label&quot;:&quot;\\u041d\\u0430\\u0437\\u0430\\u0434&quot;,&quot;step_icon_shape&quot;:&quot;none&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"21265\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"edd70fa\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Kelyanmedia\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_f4f2886 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\" data-previousbutton=\"\" data-nextbutton=\"\" data-iconurl=\"\" data-iconlibrary=\"fas fa-star\" data-icon=\"&lt;svg class=&quot;e-font-icon-svg e-fas-star&quot; viewBox=&quot;0 0 576 512&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;&gt;&lt;path d=&quot;M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z&quot;&gt;&lt;\/path&gt;&lt;\/svg&gt;\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_b6379c9 elementor-col-100\">\n\t\t\t\t\tWhat exactly do you need?\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-checkbox elementor-field-group elementor-column elementor-field-group-services elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-services\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tWhat exactly do you need?\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  elementor-subgroup-inline\"><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"\u041d\u0430\u0441\u0442\u0440\u043e\u0439\u043a\u0430 Google Ads\" id=\"form-field-services-0\" name=\"form_fields[services][]\"> <label for=\"form-field-services-0\">Setting up Google Ads<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"\u0421\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u0441\u0430\u0439\u0442\u0430\" id=\"form-field-services-1\" name=\"form_fields[services][]\"> <label for=\"form-field-services-1\">Website creation<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"\u0420\u0435\u043a\u043b\u0430\u043c\u0430 \u0432 \u0441\u043e\u0446.\u0441\u0435\u0442\u044f\u0445\" id=\"form-field-services-2\" name=\"form_fields[services][]\"> <label for=\"form-field-services-2\">Advertising on social networks<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"\u041d\u0430\u0441\u0442\u0440\u043e\u0439\u043a\u0430 \u042f\u043d\u0434\u0435\u043a\u0441.\u0414\u0438\u0440\u0435\u043a\u0442\" id=\"form-field-services-3\" name=\"form_fields[services][]\"> <label for=\"form-field-services-3\">Setting up Yandex.Direct<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"\u0423\u0432\u0435\u043b\u0438\u0447\u0435\u043d\u0438\u0435 \u043a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u0430 \u043a\u043b\u0438\u0435\u043d\u0442\u043e\u0432\" id=\"form-field-services-4\" name=\"form_fields[services][]\"> <label for=\"form-field-services-4\">Increasing the number of clients<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"\u041a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u0446\u0438\u044f\" id=\"form-field-services-5\" name=\"form_fields[services][]\"> <label for=\"form-field-services-5\">Consultation<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"\u041f\u043e\u043a\u0430 \u043d\u0435 \u0437\u043d\u0430\u044e\" id=\"form-field-services-6\" name=\"form_fields[services][]\"> <label for=\"form-field-services-6\">I don&#039;t know yet<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_6efcf9d elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\" data-previousbutton=\"\" data-nextbutton=\"\" data-iconurl=\"\" data-iconlibrary=\"fas fa-star\" data-icon=\"&lt;svg class=&quot;e-font-icon-svg e-fas-star&quot; viewBox=&quot;0 0 576 512&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;&gt;&lt;path d=&quot;M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z&quot;&gt;&lt;\/path&gt;&lt;\/svg&gt;\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_1bd285c elementor-col-100\">\n\t\t\t\t\tDo you have your own website?\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-field_acbc72d elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_acbc72d\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tDo you have your own website?\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  elementor-subgroup-inline\"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\u0414\u0430\" id=\"form-field-field_acbc72d-0\" name=\"form_fields[field_acbc72d]\" required=\"required\"> <label for=\"form-field-field_acbc72d-0\">Yes<\/label><\/span><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\u041d\u0435\u0442\" id=\"form-field-field_acbc72d-1\" name=\"form_fields[field_acbc72d]\" required=\"required\"> <label for=\"form-field-field_acbc72d-1\">No<\/label><\/span><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\u041e\u043d \u0432 \u043f\u0440\u043e\u0446\u0435\u0441\u0441\u0435 \u0440\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0438\" id=\"form-field-field_acbc72d-2\" name=\"form_fields[field_acbc72d]\" required=\"required\"> <label for=\"form-field-field_acbc72d-2\">It is under development.<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_daffb27 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\" data-previousbutton=\"\" data-nextbutton=\"\" data-iconurl=\"\" data-iconlibrary=\"fas fa-star\" data-icon=\"&lt;svg class=&quot;e-font-icon-svg e-fas-star&quot; viewBox=&quot;0 0 576 512&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;&gt;&lt;path d=&quot;M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z&quot;&gt;&lt;\/path&gt;&lt;\/svg&gt;\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_423669c elementor-col-100\">\n\t\t\t\t\tHow many clients do you need per month?\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-field_f6da93e elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_f6da93e\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tHow many clients do you need per month?\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  elementor-subgroup-inline\"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\u0414\u043e 10\" id=\"form-field-field_f6da93e-0\" name=\"form_fields[field_f6da93e]\" required=\"required\"> <label for=\"form-field-field_f6da93e-0\">Up to 10<\/label><\/span><span class=\"elementor-field-option\"><input type=\"radio\" value=\"10-20\" id=\"form-field-field_f6da93e-1\" name=\"form_fields[field_f6da93e]\" required=\"required\"> <label for=\"form-field-field_f6da93e-1\">10-20<\/label><\/span><span class=\"elementor-field-option\"><input type=\"radio\" value=\"20-25\" id=\"form-field-field_f6da93e-2\" name=\"form_fields[field_f6da93e]\" required=\"required\"> <label for=\"form-field-field_f6da93e-2\">20-25<\/label><\/span><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\u0421\u0432\u044b\u0448\u0435 50\" id=\"form-field-field_f6da93e-3\" name=\"form_fields[field_f6da93e]\" required=\"required\"> <label for=\"form-field-field_f6da93e-3\">Over 50<\/label><\/span><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\u0412\u0432\u0435\u0434\u0438\u0442\u0435 \u0441\u0432\u043e\u0439 \u0432\u0430\u0440\u0438\u0430\u043d\u0442\" id=\"form-field-field_f6da93e-4\" name=\"form_fields[field_f6da93e]\" required=\"required\"> <label for=\"form-field-field_f6da93e-4\">Enter your option<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_4747175 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\" data-previousbutton=\"\" data-nextbutton=\"\" data-iconurl=\"\" data-iconlibrary=\"fas fa-star\" data-icon=\"&lt;svg class=&quot;e-font-icon-svg e-fas-star&quot; viewBox=&quot;0 0 576 512&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;&gt;&lt;path d=&quot;M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z&quot;&gt;&lt;\/path&gt;&lt;\/svg&gt;\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_4acbaff elementor-col-100\">\n\t\t\t\t\tThank you for your answers!\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-phone elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-phone\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelephone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<span class=\"ccfef-editor-intl-input\" data-id=\"form-field-phone\" data-field-id=\"f1b30a9\" data-default-country=\"uz\" data-include-countries=\"\" data-exclude-countries=\"\" data-dial-code-visibility=\"show\" data-strict-mode=\"no\" style=\"display: none;\"><\/span>\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[phone]\" id=\"form-field-phone\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_source elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_source]\" id=\"form-field-utm_source\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_content elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_content]\" id=\"form-field-utm_content\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_medium elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_medium]\" id=\"form-field-utm_medium\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_campaign elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_campaign]\" id=\"form-field-utm_campaign\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_term elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_term]\" id=\"form-field-utm_term\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Send<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9051c7d elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"9051c7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"716\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-1024x917.webp\" class=\"attachment-large size-large wp-image-21278\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-1024x917.webp 1024w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-300x269.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-768x688.webp 768w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008-13x12.webp 13w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/group-1008.webp 1481w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3be8cf6 e-flex e-con-boxed e-con e-child\" data-id=\"3be8cf6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-db3b4a8 e-con-full e-flex e-con e-child\" data-id=\"db3b4a8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0c92ea elementor-widget elementor-widget-heading\" data-id=\"f0c92ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Frequently Asked Questions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bb86e1 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"2bb86e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Place a short call-to-action there: &quot;Didn&#039;t find the answer to your question? Contact our strategist directly on Telegram, and we&#039;ll handle your case in 15 minutes.&quot; And add a button linking to the messenger.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8d232b elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"c8d232b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIyMzUxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Write in messenger<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a0b77c e-con-full e-flex e-con e-child\" data-id=\"1a0b77c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36ba746 elementor-widget elementor-widget-ucaddon_content_accordion\" data-id=\"36ba746\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_content_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Accordion -->\n<style>\/* widget: Content Accordion *\/\n\n\n\n#uc_content_accordion_elementor_36ba746 *{\n  box-sizing: border-box;\n}\n\n#uc_content_accordion_elementor_36ba746 .ue_heading_title{\n  margin:0;\n  flex-grow:1;\n  display:flex;\n  flex-direction:row;\n}\n\n#uc_content_accordion_elementor_36ba746 .uc_container .uc-heading{\n\tdisplay:flex;\n    align-items:center;\n\toverflow:hidden;\n\tcursor:pointer;  \n}\n\n#uc_content_accordion_elementor_36ba746 .uc_container .uc_content{\n    display:none;\n}\n\n#uc_content_accordion_elementor_36ba746 .uc_container .uc-heading span.ue_accordion_icon{\n\tdisplay:flex;\n    align-items:center;\n   \tjustify-content:center;\n    flex-grow:0;\n    flex-shrink:0;\n}\n\n#uc_content_accordion_elementor_36ba746 .uc_ac_box.uc-item-active span.uc_dactive{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_36ba746 .uc_ac_box:not(.uc-item-active) span.uc_active{\n\tdisplay:none;\n}\n\n#uc_content_accordion_elementor_36ba746 span.ue_accordion_icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_content_accordion_elementor_36ba746 .uc_container .uc_btn {\n    text-align: center;\n    display: inline-block;\n    text-decoration: none;\n    transition: ease-in-out all 0.25s;\n}\n\n#uc_content_accordion_elementor_36ba746 .ue-item-image img{\n  width:100%;\n  display:block;\n  object-fit:cover;\n}\n\n<\/style>\n\n<div class=\"uc_material_accordion\"  id=\"uc_content_accordion_elementor_36ba746\"  data-name=\"\" data-scroll=\"off\" data-offset=\"0\" data-closeothers=\"true\" data-set-hash=\"false\" data-transition-duration=\"400\" >\n  <div class=\"uc_container uc-items-wrapper\">\n    \n\n\t\t\n\n\n<div id=\"#ue-tab1\" class=\"uc_ac_box elementor-repeater-item-74a636e uc-item-active\" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect x=\"0.5\" y=\"0.5\" width=\"49\" height=\"49\" rx=\"24.5\" stroke=\"black\"><\/rect><path d=\"M16 26.0211V23.9789H23.9655V15H26.069V23.9789H34V26.0211H26.069V35H23.9655V26.0211H16Z\" fill=\"black\"><\/path><\/svg><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect width=\"50\" height=\"50\" rx=\"25\" fill=\"black\"><\/rect><rect x=\"16\" y=\"24\" width=\"18\" height=\"2\" fill=\"white\"><\/rect><\/svg><\/span>\n    <div class=\"ue_heading_title\">Is it possible to promote a website to Google&#039;s top rankings using development alone?<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" style='display:block'>\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>High-quality development is the 50% of success. It creates the technical foundation that Google loves. The other 50% are content strategy and link building, which we also offer as part of our integrated marketing.<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab2\" class=\"uc_ac_box elementor-repeater-item-daa8210\" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect x=\"0.5\" y=\"0.5\" width=\"49\" height=\"49\" rx=\"24.5\" stroke=\"black\"><\/rect><path d=\"M16 26.0211V23.9789H23.9655V15H26.069V23.9789H34V26.0211H26.069V35H23.9655V26.0211H16Z\" fill=\"black\"><\/path><\/svg><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect width=\"50\" height=\"50\" rx=\"25\" fill=\"black\"><\/rect><rect x=\"16\" y=\"24\" width=\"18\" height=\"2\" fill=\"white\"><\/rect><\/svg><\/span>\n    <div class=\"ue_heading_title\">Do you help with .UZ domain registration and hosting?<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>Yes, we handle all technical issues: from registration at the UZINFOCOM center to setting up servers in TAS-IX for maximum access speed from Uzbekistan.<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n\n\n\n\n<div id=\"#ue-tab3\" class=\"uc_ac_box elementor-repeater-item-40bbe2e\" style=\"background-color:;\">\n  <a href=\"javascript:void(0)\" class=\"uc-heading uc_trigger\" role=\"button\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect x=\"0.5\" y=\"0.5\" width=\"49\" height=\"49\" rx=\"24.5\" stroke=\"black\"><\/rect><path d=\"M16 26.0211V23.9789H23.9655V15H26.069V23.9789H34V26.0211H26.069V35H23.9655V26.0211H16Z\" fill=\"black\"><\/path><\/svg><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 50 50\" fill=\"none\"><rect width=\"50\" height=\"50\" rx=\"25\" fill=\"black\"><\/rect><rect x=\"16\" y=\"24\" width=\"18\" height=\"2\" fill=\"white\"><\/rect><\/svg><\/span>\n    <div class=\"ue_heading_title\">Will my site be visible in Google AI reviews?<\/div>\n  <\/a>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                        \n              <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>We specifically structure content and technical tags so that Google&#039;s Gemini and SGE algorithms can easily read the information and suggest your business as the best answer to user queries.<\/p><\/div>\n      \n              \n      <\/div> \n<\/div>\n\n  <\/div>\n<\/div>\n\n\n<!-- end Content Accordion -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31bc6ae elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"31bc6ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIyMzUxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Calculate growth potential<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f49a3f elementor-widget elementor-widget-template\" data-id=\"9f49a3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"21531\" class=\"elementor elementor-21531\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-e2da926 e-flex e-con-boxed e-con e-parent\" data-id=\"e2da926\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f34c530 elementor-widget elementor-widget-heading\" data-id=\"f34c530\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bed5015 e-con-full e-flex e-con e-child\" data-id=\"bed5015\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-948557b e-con-full e-flex e-con e-child\" data-id=\"948557b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16ce4ed elementor-widget elementor-widget-heading\" data-id=\"16ce4ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Submit a request<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-deb6772 elementor-widget elementor-widget-heading\" data-id=\"deb6772\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Submit a request, and our expert will conduct an express audit of your niche in Tashkent and prepare a media plan within 24 hours.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9e78d4 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"a9e78d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;50&quot;,&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width_tablet&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"21531\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"a9e78d4\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Kelyanmedia\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-md-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-phone elementor-col-50 elementor-md-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-phone\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelephone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<span class=\"ccfef-editor-intl-input\" data-id=\"form-field-phone\" data-field-id=\"f1b30a9\" data-default-country=\"uz\" data-include-countries=\"\" data-exclude-countries=\"\" data-dial-code-visibility=\"show\" data-strict-mode=\"no\" style=\"display: none;\"><\/span>\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[phone]\" id=\"form-field-phone\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_a56030d elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_a56030d]\" id=\"form-field-field_a56030d\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\">\n\t\t\t\t<label for=\"form-field-field_a56030d\">Consent to the processing of personal data<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_source elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_source]\" id=\"form-field-utm_source\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_medium elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_medium]\" id=\"form-field-utm_medium\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_content elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_content]\" id=\"form-field-utm_content\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_campaign elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_campaign]\" id=\"form-field-utm_campaign\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-utm_term elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[utm_term]\" id=\"form-field-utm_term\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-50 e-form__buttons elementor-md-100\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get a growth plan<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0db289 elementor-align-justify elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-button\" data-id=\"e0db289\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/telegram.me\/kelyanmedia_admin\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Write directly to Telegram<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6250250 e-con-full e-flex e-con e-child\" data-id=\"6250250\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-50f9eec e-con-full e-flex e-con e-child\" data-id=\"50f9eec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8884d5c elementor-widget elementor-widget-heading\" data-id=\"8884d5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Or fill out a 4-step brief<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06f0a08 elementor-widget elementor-widget-heading\" data-id=\"06f0a08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Submit a request, and our expert will conduct an express audit of your niche in Tashkent and prepare a media plan within 24 hours.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f05d75 elementor-align-justify elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"8f05d75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI0MTMxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M21 12L16 7M21 12L16 17M21 12H3\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Fill out the brief<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25142a4 e-con-full e-flex e-con e-child\" data-id=\"25142a4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7507a4c elementor-widget elementor-widget-icon-box\" data-id=\"7507a4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"tel:+998333393334\" >\n\t\t\t\t\t\t\t+998 33 339 3334\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tContact phone number:\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0258b0f elementor-widget elementor-widget-icon-box\" data-id=\"0258b0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"mailto:kelyanmedia@gmail.com\" >\n\t\t\t\t\t\t\tkelyanmedia@gmail.com\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tE-mail:\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91f45f9 elementor-widget elementor-widget-icon-box\" data-id=\"91f45f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/yandex.uz\/maps\/-\/CLxNiEpp\" target=\"_blank\" >\n\t\t\t\t\t\t\tTashkent, Yashnabad district, st. Elbeka, 146\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOur address:\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03aead0 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"03aead0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"305\" height=\"298\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/qwf12topology-1.webp\" class=\"attachment-large size-large wp-image-21546\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/qwf12topology-1.webp 305w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/qwf12topology-1-300x293.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/qwf12topology-1-12x12.webp 12w\" sizes=\"(max-width: 305px) 100vw, 305px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da6ced4 elementor-widget elementor-widget-template\" data-id=\"da6ced4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"21594\" class=\"elementor elementor-21594\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<a class=\"elementor-element elementor-element-676ef61 e-con-full e-flex e-con e-parent\" data-id=\"676ef61\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/maps.app.goo.gl\/uxiUt1s7Q6C4hWbW8\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f29c6a elementor-widget__width-inherit elementor-widget elementor-widget-google_maps\" data-id=\"4f29c6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=%D0%A2%D0%B0%D1%88%D0%BA%D0%B5%D0%BD%D1%82%2C%20%D0%AD%D0%BB%D1%8C%D0%B1%D0%B5%D0%BA%D0%B0%20146&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Tashkent, Elbeka 146\"\n\t\t\t\t\taria-label=\"Tashkent, Elbeka 146\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01b7567 elementor-position-inline-start elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"01b7567\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100\" height=\"100\" viewbox=\"0 0 100 100\" fill=\"none\"><path d=\"M100 50C100 77.6142 77.6142 100 50 100C22.3858 100 0 77.6142 0 50C0 22.3858 22.3858 0 50 0C77.6142 0 100 22.3858 100 50Z\" fill=\"#FF8060\" fill-opacity=\"0.2\"><\/path><circle cx=\"51\" cy=\"50\" r=\"35\" fill=\"#FF8060\" fill-opacity=\"0.5\"><\/circle><circle cx=\"50\" cy=\"50\" r=\"15\" fill=\"#FF8060\"><\/circle><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tElbek Street, 146\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-109be76 elementor-widget elementor-widget-template\" data-id=\"109be76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"21734\" class=\"elementor elementor-21734\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cbf3df7 e-flex e-con-boxed e-con e-child\" data-id=\"6cbf3df7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d4260f7 elementor-widget elementor-widget-heading\" data-id=\"7d4260f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">About our agency<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d6d1c6 e-con-full e-flex e-con e-child\" data-id=\"4d6d1c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-28066c3 e-con-full e-flex e-con e-child\" data-id=\"28066c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d3c1920 elementor-widget elementor-widget-heading\" data-id=\"7d3c1920\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">A comprehensive digital agency in Tashkent: Your online growth <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c5730b1 elementor-widget elementor-widget-heading\" data-id=\"1c5730b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Welcome to KelyanMedia, a Tashkent-based marketing agency that doesn&#039;t just &quot;do marketing&quot;\u2014it takes responsibility for the financial results of your business. Since 2020, we&#039;ve been focused on ensuring every soum invested in promotion generates measurable revenue and increases your market share in Uzbekistan. If you&#039;re looking for a reliable partner who will translate your business goals into effective digital tools (whether SEO, SMM, or contextual advertising), you&#039;ve come to the right place. We&#039;re ready to get started with a free audit of your current strategy right now.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a47eb90 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7a47eb90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/img_1425-1-1024x576.webp\" class=\"attachment-large size-large wp-image-23910\" alt=\"\" srcset=\"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/img_1425-1-1024x576.webp 1024w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/img_1425-1-300x169.webp 300w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/img_1425-1-768x432.webp 768w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/img_1425-1-18x10.webp 18w, https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/04\/img_1425-1.webp 1106w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d18d2e e-con-full e-flex e-con e-child\" data-id=\"3d18d2e\" data-element_type=\"container\" data-e-type=\"container\" id=\"about_readmore\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de977bd elementor-widget elementor-widget-heading\" data-id=\"de977bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">A comprehensive digital agency in Tashkent: Your online growth <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c45ed48 elementor-widget elementor-widget-heading\" data-id=\"c45ed48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">We&#039;ll rank your website among the top organic search results for your target queries. Our strategy is based on a thorough analysis of competitors in Uzbekistan and website adaptation to Google algorithms. In fact, most of our clients experience a steady flow of leads for the first time after implementing our comprehensive SEO.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7decd7b elementor-widget elementor-widget-heading\" data-id=\"7decd7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Our key areas of work for local SEO:<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-752ab82 e-grid e-con-full e-con e-child\" data-id=\"752ab82\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-435f98e elementor-widget elementor-widget-text-editor\" data-id=\"435f98e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1. Local SEO and Geotargeting: We perform in-depth GEO optimization of your presence. This includes not only targeting queries related to Tashkent and the surrounding region, but also setting up regional subdomains (if necessary) and precisely defining your target geographic area. We guarantee that users in your area will find you first.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2f275d elementor-widget elementor-widget-text-editor\" data-id=\"c2f275d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2. Technical Audit and Speed: Eliminating all technical errors that hinder site growth and crawling by search engines. Particular attention is paid to loading speed (Core Web Vitals), mobile responsiveness, and clean code. A fast site ranks better.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be01c0f elementor-widget elementor-widget-text-editor\" data-id=\"be01c0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>3. Content Strategy and EEAT: Creating expert, useful content that both Google and users trust. We develop a content plan based on the real needs of the Uzbek audience, focusing on your Expertise, Experience, Authority, and Trust (EEAT).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-608c029 elementor-widget elementor-widget-text-editor\" data-id=\"608c029\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>4. Google Business Profile (GBP) Optimization: For local businesses in Tashkent, GBP is undoubtedly one of the most important tools. We set up, verify, and regularly optimize your profile: we manage reviews, update your business hours, and add photos and services to ensure they are included in the Google Maps Local Pack.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21bb53d elementor-widget elementor-widget-text-editor\" data-id=\"21bb53d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>5. Off-Page Optimization and Local Links: We build a high-quality and natural link profile using authoritative local resources in Uzbekistan, news portals, and thematic directories. This increases Google&#039;s trust in your domain.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b194554 elementor-widget elementor-widget-text-editor\" data-id=\"b194554\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>6. Analytics and Continuous Testing: SEO is not a one-time adjustment, but an ongoing process. We use web analytics tools to track rankings, conversions, and user behavior to quickly make adjustments and ensure sustainable traffic growth.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-defa0ed e-grid e-con-full e-con e-child\" data-id=\"defa0ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-acf1224 elementor-widget elementor-widget-text-editor\" data-id=\"acf1224\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dentistry in Tashkent VEDA STOM<\/strong>Thanks to a comprehensive SEO strategy and effective contextual advertising optimization, our team of professionals implemented a project that increased the number of targeted inquiries (leads) by 67% in 10 months. Companies partnering with our marketing agency achieve higher promotion results than the market, as confirmed by successful cases and marketing expertise.<\/p><p>We pride ourselves on building long-term partnerships.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a93c4e4 elementor-widget elementor-widget-text-editor\" data-id=\"a93c4e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Taxi service Alex taxi<\/strong>After auditing and launching a new targeted campaign and implementing effective solutions, we were able to reduce the cost per lead to 0.27$ during the first quarter. Our Tashkent-based marketing agency has been working with similar projects for over five years, allowing us to offer companies proven and effective promotion strategies and comprehensive marketing services.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d89e719 elementor-widget elementor-widget-heading\" data-id=\"d89e719\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Our Results and Trust<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c03b7d0 e-grid e-con-full e-con e-child\" data-id=\"c03b7d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b4e026 elementor-widget elementor-widget-text-editor\" data-id=\"8b4e026\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>SMM and Targeted Advertising<\/strong><\/p><p><br \/>An active social media presence, especially on Telegram and Instagram, is critical for the Uzbek market. We don&#039;t just post pretty pictures; we build sales funnels that convert followers into customers. We certainly know how to reach your target audience.<\/p><ul role=\"list\"><li><strong>Creative development<\/strong>: Creating catchy content for advertising.<\/li><li><strong>Community Management<\/strong>: Increased brand engagement and loyalty.<\/li><li><strong>Setting up targeting<\/strong>: Accurate targeting of the solvent audience.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8619b3e elementor-widget elementor-widget-text-editor\" data-id=\"8619b3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Contextual Advertising (PPC)<\/strong><\/p><p><br \/>Fast and transparent sales. We work with Google Ads, optimizing campaigns to minimize customer acquisition cost (CPL) and maximize return on investment (ROI). We constantly test hypotheses, which is interesting, to find the most effective advertising channel specifically for your product.<\/p><ul role=\"list\"><li><strong>Audit and optimization<\/strong>: Reduction of non-targeted expenses.<\/li><li><strong>Remarketing<\/strong>: Return users who have already been to your site.<\/li><li><strong>Search and display campaigns<\/strong>: Audience coverage at all stages of the funnel.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49bc03b elementor-widget elementor-widget-text-editor\" data-id=\"49bc03b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Your Journey to Growth Starts Here<\/strong><\/p><p><br \/>Ready to learn how a leading marketing agency in Tashkent can revolutionize your online business?<br \/>Don&#039;t waste money on ineffective strategies. Start with a no-obligation consultation. We&#039;ll conduct a free express audit of your current digital presence and provide specific recommendations for immediate improvement.<\/p><p>Submit a request and our project manager will contact you to discuss your growth today.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cb28a51 elementor-widget elementor-widget-read-more-button\" data-id=\"2cb28a51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"read-more-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"read-more-widget-wrapper\">\n            <button class=\"read-more-button elementor-button elementor-size-sm\" data-target-id=\"about_readmore\" data-text-show=\"\u041f\u043e\u043a\u0430\u0437\u0430\u0442\u044c \u0431\u043e\u043b\u044c\u0448\u0435\" data-text-hide=\"\u0421\u043a\u0440\u044b\u0442\u044c\" data-animation-duration=\"\" role=\"button\">\n                                <span class=\"elementor-button-text\">Show more<\/span>\n                            <\/button>\n        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0438 \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u0441\u0430\u0439\u0442\u043e\u0432 \u0432 \u0422\u0430\u0448\u043a\u0435\u043d\u0442\u0435 \u041a\u0430\u0436\u0434\u0430\u044f \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u044f, \u0437\u0430\u043d\u0438\u043c\u0430\u044e\u0449\u0430\u044f\u0441\u044f \u0442\u0435\u043c \u0438\u043b\u0438 \u0438\u043d\u044b\u043c \u0431\u0438\u0437\u043d\u0435\u0441\u043e\u043c, \u0441\u043e \u0432\u0440\u0435\u043c\u0435\u043d\u0435\u043c \u043f\u0440\u0438\u0445\u043e\u0434\u0438\u0442 \u043a \u0442\u043e\u043c\u0443, \u0447\u0442\u043e\u0431\u044b \u0441\u043e\u0437\u0434\u0430\u0442\u044c \u0441\u0430\u0439\u0442. \u0421\u0432\u043e\u0435\u0432\u0440\u0435\u043c\u0435\u043d\u043d\u043e \u0441\u043e\u0437\u0434\u0430\u043d\u043d\u044b\u0439 \u0441\u0430\u0439\u0442 \u2013\u043d\u0435 \u0442\u043e\u043b\u044c\u043a\u043e \u0432\u0438\u0437\u0438\u0442\u043a\u0430 \u0438 \u043b\u0438\u0446\u043e \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u0438, \u043d\u043e \u0434\u043e\u043f\u043e\u043b\u043d\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0435 \u043f\u0440\u043e\u0434\u0430\u0436\u0438. \u0420\u0430\u0441\u0441\u0447\u0438\u0442\u0430\u0442\u044c \u043f\u0440\u043e\u0435\u043a\u0442 \u041f\u043e\u0441\u043c\u043e\u0442\u0440\u0435\u0442\u044c \u043a\u0435\u0439\u0441\u044b \u041a\u0430\u043a\u0438\u0435 \u0437\u0430\u0434\u0430\u0447\u0438 \u0440\u0435\u0448\u0430\u0435\u0442 \u0432\u0435\u0431-\u0441\u0430\u0439\u0442? \u041f\u043e\u043b\u0443\u0447\u0438\u0442\u044c \u043a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u0446\u0438\u044e \u0423\u0432\u0435\u043b\u0438\u0447\u0435\u043d\u0438\u0435 \u043f\u0440\u0438\u0431\u044b\u043b\u0438 \u041e\u0442 \u0432\u043d\u0435\u0448\u043d\u0435\u0433\u043e \u0432\u0438\u0434\u0430 \u043b\u0435\u043d\u0434\u0438\u043d\u0433\u0430 \u0437\u0430\u0432\u0438\u0441\u0438\u0442 \u0434\u043e\u0432\u0435\u0440\u0438\u0435 \u0438 \u0438\u043d\u0442\u0435\u0440\u0435\u0441 \u043a\u043b\u0438\u0435\u043d\u0442\u043e\u0432. \u0414\u0438\u0437\u0430\u0439\u043d [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":14090,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-22131","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0438 \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u0441\u0430\u0439\u0442\u043e\u0432 \u0432 \u0422\u0430\u0448\u043a\u0435\u043d\u0442\u0435 (new) - Kelyanmedia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kelyanmedia.uz\/en\/team\/obidzhon\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0438 \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u0441\u0430\u0439\u0442\u043e\u0432 \u0432 \u0422\u0430\u0448\u043a\u0435\u043d\u0442\u0435 (new) - Kelyanmedia\" \/>\n<meta property=\"og:description\" content=\"\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0438 \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u0441\u0430\u0439\u0442\u043e\u0432 \u0432 \u0422\u0430\u0448\u043a\u0435\u043d\u0442\u0435 \u041a\u0430\u0436\u0434\u0430\u044f \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u044f, \u0437\u0430\u043d\u0438\u043c\u0430\u044e\u0449\u0430\u044f\u0441\u044f \u0442\u0435\u043c \u0438\u043b\u0438 \u0438\u043d\u044b\u043c \u0431\u0438\u0437\u043d\u0435\u0441\u043e\u043c, \u0441\u043e \u0432\u0440\u0435\u043c\u0435\u043d\u0435\u043c \u043f\u0440\u0438\u0445\u043e\u0434\u0438\u0442 \u043a \u0442\u043e\u043c\u0443, \u0447\u0442\u043e\u0431\u044b \u0441\u043e\u0437\u0434\u0430\u0442\u044c \u0441\u0430\u0439\u0442. \u0421\u0432\u043e\u0435\u0432\u0440\u0435\u043c\u0435\u043d\u043d\u043e \u0441\u043e\u0437\u0434\u0430\u043d\u043d\u044b\u0439 \u0441\u0430\u0439\u0442 \u2013\u043d\u0435 \u0442\u043e\u043b\u044c\u043a\u043e \u0432\u0438\u0437\u0438\u0442\u043a\u0430 \u0438 \u043b\u0438\u0446\u043e \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u0438, \u043d\u043e \u0434\u043e\u043f\u043e\u043b\u043d\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0435 \u043f\u0440\u043e\u0434\u0430\u0436\u0438. \u0420\u0430\u0441\u0441\u0447\u0438\u0442\u0430\u0442\u044c \u043f\u0440\u043e\u0435\u043a\u0442 \u041f\u043e\u0441\u043c\u043e\u0442\u0440\u0435\u0442\u044c \u043a\u0435\u0439\u0441\u044b \u041a\u0430\u043a\u0438\u0435 \u0437\u0430\u0434\u0430\u0447\u0438 \u0440\u0435\u0448\u0430\u0435\u0442 \u0432\u0435\u0431-\u0441\u0430\u0439\u0442? \u041f\u043e\u043b\u0443\u0447\u0438\u0442\u044c \u043a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u0446\u0438\u044e \u0423\u0432\u0435\u043b\u0438\u0447\u0435\u043d\u0438\u0435 \u043f\u0440\u0438\u0431\u044b\u043b\u0438 \u041e\u0442 \u0432\u043d\u0435\u0448\u043d\u0435\u0433\u043e \u0432\u0438\u0434\u0430 \u043b\u0435\u043d\u0434\u0438\u043d\u0433\u0430 \u0437\u0430\u0432\u0438\u0441\u0438\u0442 \u0434\u043e\u0432\u0435\u0440\u0438\u0435 \u0438 \u0438\u043d\u0442\u0435\u0440\u0435\u0441 \u043a\u043b\u0438\u0435\u043d\u0442\u043e\u0432. \u0414\u0438\u0437\u0430\u0439\u043d [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kelyanmedia.uz\/en\/team\/obidzhon\/\" \/>\n<meta property=\"og:site_name\" content=\"Kelyanmedia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kelyanmedia\/?locale=ru_RU\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-25T21:06:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"60 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kelyanmedia.uz\\\/team\\\/obidzhon\\\/\",\"url\":\"https:\\\/\\\/kelyanmedia.uz\\\/team\\\/obidzhon\\\/\",\"name\":\"\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0438 \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u0441\u0430\u0439\u0442\u043e\u0432 \u0432 \u0422\u0430\u0448\u043a\u0435\u043d\u0442\u0435 (new) - Kelyanmedia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kelyanmedia.uz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kelyanmedia.uz\\\/team\\\/obidzhon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kelyanmedia.uz\\\/team\\\/obidzhon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kelyanmedia.uz\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/jhe45678i.svg\",\"datePublished\":\"2026-01-12T11:59:55+00:00\",\"dateModified\":\"2026-01-25T21:06:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kelyanmedia.uz\\\/team\\\/obidzhon\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kelyanmedia.uz\\\/team\\\/obidzhon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kelyanmedia.uz\\\/team\\\/obidzhon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kelyanmedia.uz\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/jhe45678i.svg\",\"contentUrl\":\"https:\\\/\\\/kelyanmedia.uz\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/jhe45678i.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kelyanmedia.uz\\\/team\\\/obidzhon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/kelyanmedia.uz\\\/team\\\/obidzhon\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0423\u0441\u043b\u0443\u0433\u0438\",\"item\":\"https:\\\/\\\/kelyanmedia.uz\\\/?page_id=14090\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0438 \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u0441\u0430\u0439\u0442\u043e\u0432 \u0432 \u0422\u0430\u0448\u043a\u0435\u043d\u0442\u0435 (new)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kelyanmedia.uz\\\/#website\",\"url\":\"https:\\\/\\\/kelyanmedia.uz\\\/\",\"name\":\"Kelyanmedia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kelyanmedia.uz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kelyanmedia.uz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kelyanmedia.uz\\\/#organization\",\"name\":\"Kelyanmedia\",\"url\":\"https:\\\/\\\/kelyanmedia.uz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kelyanmedia.uz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kelyanmedia.uz\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-km-1.webp\",\"contentUrl\":\"https:\\\/\\\/kelyanmedia.uz\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-km-1.webp\",\"width\":383,\"height\":424,\"caption\":\"Kelyanmedia\"},\"image\":{\"@id\":\"https:\\\/\\\/kelyanmedia.uz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kelyanmedia\\\/?locale=ru_RU\",\"https:\\\/\\\/www.instagram.com\\\/kelyanmedia\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Website development and creation in Tashkent (new) - Kelyanmedia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kelyanmedia.uz\/en\/team\/obidzhon\/","og_locale":"en_US","og_type":"article","og_title":"\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0438 \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u0441\u0430\u0439\u0442\u043e\u0432 \u0432 \u0422\u0430\u0448\u043a\u0435\u043d\u0442\u0435 (new) - Kelyanmedia","og_description":"\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0438 \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u0441\u0430\u0439\u0442\u043e\u0432 \u0432 \u0422\u0430\u0448\u043a\u0435\u043d\u0442\u0435 \u041a\u0430\u0436\u0434\u0430\u044f \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u044f, \u0437\u0430\u043d\u0438\u043c\u0430\u044e\u0449\u0430\u044f\u0441\u044f \u0442\u0435\u043c \u0438\u043b\u0438 \u0438\u043d\u044b\u043c \u0431\u0438\u0437\u043d\u0435\u0441\u043e\u043c, \u0441\u043e \u0432\u0440\u0435\u043c\u0435\u043d\u0435\u043c \u043f\u0440\u0438\u0445\u043e\u0434\u0438\u0442 \u043a \u0442\u043e\u043c\u0443, \u0447\u0442\u043e\u0431\u044b \u0441\u043e\u0437\u0434\u0430\u0442\u044c \u0441\u0430\u0439\u0442. \u0421\u0432\u043e\u0435\u0432\u0440\u0435\u043c\u0435\u043d\u043d\u043e \u0441\u043e\u0437\u0434\u0430\u043d\u043d\u044b\u0439 \u0441\u0430\u0439\u0442 \u2013\u043d\u0435 \u0442\u043e\u043b\u044c\u043a\u043e \u0432\u0438\u0437\u0438\u0442\u043a\u0430 \u0438 \u043b\u0438\u0446\u043e \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u0438, \u043d\u043e \u0434\u043e\u043f\u043e\u043b\u043d\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0435 \u043f\u0440\u043e\u0434\u0430\u0436\u0438. \u0420\u0430\u0441\u0441\u0447\u0438\u0442\u0430\u0442\u044c \u043f\u0440\u043e\u0435\u043a\u0442 \u041f\u043e\u0441\u043c\u043e\u0442\u0440\u0435\u0442\u044c \u043a\u0435\u0439\u0441\u044b \u041a\u0430\u043a\u0438\u0435 \u0437\u0430\u0434\u0430\u0447\u0438 \u0440\u0435\u0448\u0430\u0435\u0442 \u0432\u0435\u0431-\u0441\u0430\u0439\u0442? \u041f\u043e\u043b\u0443\u0447\u0438\u0442\u044c \u043a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u0446\u0438\u044e \u0423\u0432\u0435\u043b\u0438\u0447\u0435\u043d\u0438\u0435 \u043f\u0440\u0438\u0431\u044b\u043b\u0438 \u041e\u0442 \u0432\u043d\u0435\u0448\u043d\u0435\u0433\u043e \u0432\u0438\u0434\u0430 \u043b\u0435\u043d\u0434\u0438\u043d\u0433\u0430 \u0437\u0430\u0432\u0438\u0441\u0438\u0442 \u0434\u043e\u0432\u0435\u0440\u0438\u0435 \u0438 \u0438\u043d\u0442\u0435\u0440\u0435\u0441 \u043a\u043b\u0438\u0435\u043d\u0442\u043e\u0432. \u0414\u0438\u0437\u0430\u0439\u043d [&hellip;]","og_url":"https:\/\/kelyanmedia.uz\/en\/team\/obidzhon\/","og_site_name":"Kelyanmedia","article_publisher":"https:\/\/www.facebook.com\/kelyanmedia\/?locale=ru_RU","article_modified_time":"2026-01-25T21:06:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"60 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kelyanmedia.uz\/team\/obidzhon\/","url":"https:\/\/kelyanmedia.uz\/team\/obidzhon\/","name":"Website development and creation in Tashkent (new) - Kelyanmedia","isPartOf":{"@id":"https:\/\/kelyanmedia.uz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kelyanmedia.uz\/team\/obidzhon\/#primaryimage"},"image":{"@id":"https:\/\/kelyanmedia.uz\/team\/obidzhon\/#primaryimage"},"thumbnailUrl":"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/jhe45678i.svg","datePublished":"2026-01-12T11:59:55+00:00","dateModified":"2026-01-25T21:06:57+00:00","breadcrumb":{"@id":"https:\/\/kelyanmedia.uz\/team\/obidzhon\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kelyanmedia.uz\/team\/obidzhon\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kelyanmedia.uz\/team\/obidzhon\/#primaryimage","url":"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/jhe45678i.svg","contentUrl":"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2026\/01\/jhe45678i.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/kelyanmedia.uz\/team\/obidzhon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/kelyanmedia.uz\/team\/obidzhon\/"},{"@type":"ListItem","position":2,"name":"\u0423\u0441\u043b\u0443\u0433\u0438","item":"https:\/\/kelyanmedia.uz\/?page_id=14090"},{"@type":"ListItem","position":3,"name":"\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0438 \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u0441\u0430\u0439\u0442\u043e\u0432 \u0432 \u0422\u0430\u0448\u043a\u0435\u043d\u0442\u0435 (new)"}]},{"@type":"WebSite","@id":"https:\/\/kelyanmedia.uz\/#website","url":"https:\/\/kelyanmedia.uz\/","name":"Kelyanmedia","description":"","publisher":{"@id":"https:\/\/kelyanmedia.uz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kelyanmedia.uz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kelyanmedia.uz\/#organization","name":"Kelyanmedia","url":"https:\/\/kelyanmedia.uz\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kelyanmedia.uz\/#\/schema\/logo\/image\/","url":"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2024\/07\/logo-km-1.webp","contentUrl":"https:\/\/kelyanmedia.uz\/wp-content\/uploads\/2024\/07\/logo-km-1.webp","width":383,"height":424,"caption":"Kelyanmedia"},"image":{"@id":"https:\/\/kelyanmedia.uz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kelyanmedia\/?locale=ru_RU","https:\/\/www.instagram.com\/kelyanmedia\/"]}]}},"_links":{"self":[{"href":"https:\/\/kelyanmedia.uz\/en\/wp-json\/wp\/v2\/pages\/22131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kelyanmedia.uz\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kelyanmedia.uz\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kelyanmedia.uz\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kelyanmedia.uz\/en\/wp-json\/wp\/v2\/comments?post=22131"}],"version-history":[{"count":121,"href":"https:\/\/kelyanmedia.uz\/en\/wp-json\/wp\/v2\/pages\/22131\/revisions"}],"predecessor-version":[{"id":22995,"href":"https:\/\/kelyanmedia.uz\/en\/wp-json\/wp\/v2\/pages\/22131\/revisions\/22995"}],"up":[{"embeddable":true,"href":"https:\/\/kelyanmedia.uz\/en\/wp-json\/wp\/v2\/pages\/14090"}],"wp:attachment":[{"href":"https:\/\/kelyanmedia.uz\/en\/wp-json\/wp\/v2\/media?parent=22131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}